{"id":100,"count":1,"description":"","link":"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/","name":"standar resep","slug":"standar-resep","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>standar resep Archives - Blog AhliGiziID<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"standar resep Archives - Blog AhliGiziID\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AhliGiziID\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ahligiziid\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/\",\"url\":\"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/\",\"name\":\"standar resep Archives - Blog AhliGiziID\",\"isPartOf\":{\"@id\":\"https:\/\/ahligizi.id\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ahligizi.id\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"standar resep\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ahligizi.id\/blog\/#website\",\"url\":\"https:\/\/ahligizi.id\/blog\/\",\"name\":\"Blog AhliGiziID\",\"description\":\"Menyajikan Informasi Gizi yang Renyah dan Ilmiah\",\"publisher\":{\"@id\":\"https:\/\/ahligizi.id\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ahligizi.id\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ahligizi.id\/blog\/#organization\",\"name\":\"AhliGiziID\",\"url\":\"https:\/\/ahligizi.id\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ahligizi.id\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ahligizi.id\/blog\/wp-content\/uploads\/2019\/11\/ahligizi_logo.png\",\"contentUrl\":\"https:\/\/ahligizi.id\/blog\/wp-content\/uploads\/2019\/11\/ahligizi_logo.png\",\"width\":2370,\"height\":664,\"caption\":\"AhliGiziID\"},\"image\":{\"@id\":\"https:\/\/ahligizi.id\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/ahligiziid\",\"https:\/\/x.com\/ahligiziid\",\"https:\/\/intagram.com\/ahligiziid\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"standar resep Archives - Blog AhliGiziID","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/","og_locale":"en_US","og_type":"article","og_title":"standar resep Archives - Blog AhliGiziID","og_url":"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/","og_site_name":"Blog AhliGiziID","twitter_card":"summary_large_image","twitter_site":"@ahligiziid","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/","url":"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/","name":"standar resep Archives - Blog AhliGiziID","isPartOf":{"@id":"https:\/\/ahligizi.id\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ahligizi.id\/blog\/tag\/standar-resep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ahligizi.id\/blog\/"},{"@type":"ListItem","position":2,"name":"standar resep"}]},{"@type":"WebSite","@id":"https:\/\/ahligizi.id\/blog\/#website","url":"https:\/\/ahligizi.id\/blog\/","name":"Blog AhliGiziID","description":"Menyajikan Informasi Gizi yang Renyah dan Ilmiah","publisher":{"@id":"https:\/\/ahligizi.id\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ahligizi.id\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ahligizi.id\/blog\/#organization","name":"AhliGiziID","url":"https:\/\/ahligizi.id\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ahligizi.id\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ahligizi.id\/blog\/wp-content\/uploads\/2019\/11\/ahligizi_logo.png","contentUrl":"https:\/\/ahligizi.id\/blog\/wp-content\/uploads\/2019\/11\/ahligizi_logo.png","width":2370,"height":664,"caption":"AhliGiziID"},"image":{"@id":"https:\/\/ahligizi.id\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/ahligiziid","https:\/\/x.com\/ahligiziid","https:\/\/intagram.com\/ahligiziid"]}]}},"_links":{"self":[{"href":"https:\/\/ahligizi.id\/blog\/wp-json\/wp\/v2\/tags\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ahligizi.id\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ahligizi.id\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ahligizi.id\/blog\/wp-json\/wp\/v2\/posts?tags=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}